{"id":75286,"date":"2024-08-20T21:31:34","date_gmt":"2024-08-21T02:31:34","guid":{"rendered":"https:\/\/catchthefever.com\/affilies\/"},"modified":"2025-09-17T12:29:34","modified_gmt":"2025-09-17T17:29:34","slug":"affilies","status":"publish","type":"page","link":"https:\/\/catchthefever.com\/fr\/affilies\/","title":{"rendered":"Affili\u00e9s"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"75286\" class=\"elementor elementor-75286 elementor-3032\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d13fbcd elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"d13fbcd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-691355f\" data-id=\"691355f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ecd315 elementor-widget elementor-widget-spacer\" data-id=\"5ecd315\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-481a78a elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"481a78a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2a00ff8 elementor-invisible\" data-id=\"2a00ff8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8dd187 elementor-widget elementor-widget-heading\" data-id=\"a8dd187\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gagnez jusqu'\u00e0\n25 000 $ en utilisant les produits CTF !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed2382c elementor-widget elementor-widget-text-editor\" data-id=\"ed2382c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous r\u00e9compensons les p\u00eacheurs aux \u00c9tats-Unis pour leurs comp\u00e9tences lorsqu&rsquo;ils p\u00eachent avec Catch The Fever. Les gains peuvent \u00eatre consid\u00e9rables. D\u00e9couvrez si vous \u00eates \u00e9ligible, comment participer, quelles s\u00e9ries de cannes et\/ou v\u00eatements vous pouvez utiliser dans quelles circonstances pour potentiellement gagner jusqu&rsquo;\u00e0 25 000 $ de Catch The Fever.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4976c51 elementor-widget elementor-widget-text-editor\" data-id=\"4976c51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Des questions ? Nous sommes toujours l\u00e0 pour vous aider et rendre nos programmes de r\u00e9compenses accessibles. Appelez-nous ou visitez notre page de contact.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5474d30\" data-id=\"5474d30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f30537 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"2f30537\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"46\" height=\"46\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-2.png\" class=\"attachment-full size-full wp-image-49\" alt=\"\" title=\"Icon (2) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-2.png 46w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-2-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-2-10x10.webp 10w\" sizes=\"(max-width: 46px) 100vw, 46px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Prix jusqu'\u00e0 25 000 $<\/h3><p class=\"elementor-image-box-description\">Vous p\u00eachez d\u00e9j\u00e0, vous avez la passion, rendez-la plus douce avec notre programme de r\u00e9compenses. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f63d241 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"f63d241\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"47\" height=\"47\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Vector.webp\" class=\"attachment-full size-full wp-image-56\" alt=\"\" title=\"Vector - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Vector.webp 47w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Vector-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Vector-10x10.webp 10w\" sizes=\"(max-width: 47px) 100vw, 47px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">V\u00eatements et\/ou cannes<\/h3><p class=\"elementor-image-box-description\">Vous pouvez avoir une autre canne en main, nous vous donnons quand m\u00eame une chance de vous qualifier avec nos v\u00eatements. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07bca25 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"07bca25\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"47\" height=\"47\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Vector.webp\" class=\"attachment-full size-full wp-image-56\" alt=\"\" title=\"Vector - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Vector.webp 47w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Vector-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Vector-10x10.webp 10w\" sizes=\"(max-width: 47px) 100vw, 47px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Plus de 18 esp\u00e8ces de poissons<\/h3><p class=\"elementor-image-box-description\">Vous p\u00eachez d\u00e9j\u00e0 pour cela. Eau douce et eau sal\u00e9e, la liste est longue.  <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-689f8da e-flex e-con-boxed e-con e-parent\" data-id=\"689f8da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2170ec elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"e2170ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">R\u00e8gles et r\u00e8glements officiels<\/h3><p class=\"elementor-image-box-description\">Catch the fever outdoors LLC - promotion du record d'\u00c9tat : \n\nLA PROMOTION (D\u00c9FINIE CI-DESSOUS) EST DESTIN\u00c9E UNIQUEMENT AUX \u00c9TATS-UNIS ET SERA R\u00c9GIE PAR LA LOI AM\u00c9RICAINE. N'ENTREZ PAS SI VOUS N'\u00caTES PAS \u00c9LIGIBLE OU SI VOUS VOUS TROUVEZ EN DEHORS DES \u00c9TATS-UNIS AU TIME DE L'INSCRIPTION. NULLE L\u00c0 O\u00d9 ELLE EST INTERDITE. LA PARTICIPATION \u00c0 LA PROMOTION EST SOUMISE \u00c0 CES R\u00c8GLES OFFICIELLES \u00c0 TOUT MOMENT.   <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d60b813 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"d60b813\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">1. Sponsor de la promotion<\/h3><p class=\"elementor-image-box-description\">La promotion du concours de record d'\u00c9tat (la \u00ab Promotion \u00bb) est parrain\u00e9e par Catch the Fever Outdoors, LLC, dont le si\u00e8ge social est situ\u00e9 au 1458 Old Durham, Roxboro, NC 27573 (\u00ab Sponsor \u00bb). Le Sponsor et ses agences de publicit\u00e9, de promotion des ventes, juridiques et toutes les autres agences de services impliqu\u00e9es dans le d\u00e9veloppement, la production, la mise en \u0153uvre, l'administration ou l'ex\u00e9cution de la Promotion sont collectivement les \u00ab Entit\u00e9s de la Promotion \u00bb. Vous comprenez que vous fournissez des informations uniquement au Sponsor. En participant \u00e0 la Promotion, chaque Participant (d\u00e9fini ci-dessous) accepte et s'engage \u00e0 \u00eatre li\u00e9 par ces r\u00e8gles officielles de la Promotion (ces \u00ab R\u00e8gles Officielles \u00bb). Le site Web sur lequel ces R\u00e8gles Officielles sont publi\u00e9es ou tout autre support num\u00e9rique est appel\u00e9 \u00ab Site \u00bb aux fins des pr\u00e9sentes R\u00e8gles Officielles.    <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab068a4 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"ab068a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">2. \u00c9ligibilit\u00e9<\/h3><p class=\"elementor-image-box-description\">La Promotion est ouverte aux r\u00e9sidents l\u00e9gaux des \u00c9tats-Unis et du District de Columbia, \u00e0 l'exclusion des r\u00e9sidents de Porto Rico et des territoires et possessions des \u00c9tats-Unis, \u00e2g\u00e9s de dix-huit (18) ans ou plus au moment de l'inscription (chacun un \u00ab Participant \u00bb ou \u00ab vous \u00bb). La Promotion est nulle en dehors des \u00c9tats-Unis et l\u00e0 o\u00f9 la loi l'interdit. Les employ\u00e9s des Entit\u00e9s de la Promotion et les membres de leur famille imm\u00e9diate (d\u00e9finis pour ces R\u00e8gles Officielles comme les conjoints, parents, enfants, fr\u00e8res et s\u0153urs, et chacun de leurs conjoints respectifs, quel que soit leur lieu de r\u00e9sidence) ou les personnes vivant dans le m\u00eame foyer (apparent\u00e9es ou non) que l'une des personnes susmentionn\u00e9es ne sont pas \u00e9ligibles pour participer.  <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25748f8 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"25748f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">3. P\u00e9riode de promotion<\/h3><p class=\"elementor-image-box-description\">La Promotion d\u00e9bute \u00e0 00h01 heure de l'Est (\u00ab HE \u00bb) le 1er janvier 2024 et se termine \u00e0 23h59 HE le 31 d\u00e9cembre 2024 (\u00ab P\u00e9riode de Promotion \u00bb). Toutes les participations doivent \u00eatre soumises au Sponsor pendant la P\u00e9riode de Promotion. L'ordinateur du Sponsor est le dispositif officiel de chronom\u00e9trage pour cette Promotion.  <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf523dc elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"cf523dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">4. Cat\u00e9gories de promotion<\/h3><p class=\"elementor-image-box-description\">Un Participant peut participer \u00e0 la Promotion dans une ou les deux cat\u00e9gories suivantes (collectivement, les \u00ab Cat\u00e9gories de Promotion \u00bb), bien qu'un seul Prix ne sera attribu\u00e9 par Cat\u00e9gorie de Promotion pendant la P\u00e9riode de Promotion :<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5a952f elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"c5a952f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"> - cat\u00e9gorie v\u00eatements<\/h3><p class=\"elementor-image-box-description\">Le Participant doit porter un v\u00eatement officiel (par exemple, chapeaux, sweats \u00e0 capuche, bonnets, chemises ou autres v\u00eatements officiels) vendu par le Sponsor ou l'un de ses d\u00e9taillants autoris\u00e9s qui contient la marque d\u00e9pos\u00e9e, la marque ou le logo du Sponsor (\u00ab V\u00eatements Officiels \u00bb) et attraper l'une (1) des \u00ab Esp\u00e8ces \u00c9ligibles \u00bb de la liste ci-dessous qui se qualifie comme un Record d'\u00c9tat par poids. Le premier Participant pendant la P\u00e9riode de Promotion \u00e0 accomplir ce qui pr\u00e9c\u00e8de et qui se conforme pleinement \u00e0 ces R\u00e8gles Officielles (y compris toutes les exigences de v\u00e9rification du gagnant) sera \u00e9ligible pour recevoir le Prix de la Cat\u00e9gorie V\u00eatements (d\u00e9fini ci-dessous). <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32b9f7c elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"32b9f7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"> - liste des esp\u00e8ces \u00e9ligibles pour la cat\u00e9gorie v\u00eatements<\/h3><p class=\"elementor-image-box-description\">- Poisson-chat \u00e0 t\u00eate plate : (Pylodictis olivaris)<br>- Poisson-chat de rivi\u00e8re : (Ictalurus punctatus)<br>- Poisson-chat bleu de l'Arkansas : (Ictalurus furcatus)<br>- Achigan \u00e0 grande bouche : (Micropterus salmoides)<br>- Thon rouge : (Thunnus thynnus)<br>- Marlin bleu : (Makaira nigricans)<br>- Marigane blanche : (Pomoxis annularis)<br>- Marigane noire : (Pomoxis nigromaculatus)<br>- Dor\u00e9 jaune : (Sander vitreus)<br>-Saumon coho : (Oncorhynchus kisutch)<br>-Achigan \u00e0 petite bouche : (Micropterus dolomieu)<br>-Brochet du Nord : (Esox lucius)<br>-Saumon chinook : (Oncorhynchus tshawytscha)<br>-Coryph\u00e8ne : (Coryphaena hippurus)<br>-Cardeau d'\u00e9t\u00e9 : (Paralichthys dentatus)<br>-Maquereau royal : (Scomberomorus cavalla)<br>-Bar blanc : (Atractoscion nobilis)<br>-Fl\u00e9tan de Californie : (Paralichthys californicus)<br>-Truite mouchet\u00e9e : (Cynoscion nebulosus)<br>-Bar ray\u00e9 : (Morone saxatilis)<br>-Coryph\u00e8ne : (Mahi-Mahi\/ Coryphaena hippurus)<br>-Cobia : (Rachycentron Canadum)<br>-Thazard-b\u00e2tard : (Acanthomcybium Solandri)<br>-Maquereau espagnol : (Scomberomorus Maculatus)<br>-Tambour rouge : (Sciaenops Ocelltus)<br>-Crapet \u00e0 oreilles rouges \u00ab Shellcracker \u00bb : (Lepomis Microlophus)<br>-Crapet arlequin : (Lepomis Macrochirus)<br><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59f4cf9 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"59f4cf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">  - Cat\u00e9gorie de canne \u00e0 p\u00eache<\/h3><p class=\"elementor-image-box-description\">Le participant doit utiliser une canne \u00e0 p\u00eache officielle vendue par le Sponsor ou l'un de ses d\u00e9taillants autoris\u00e9s (\u00ab Canne officielle \u00bb) et capturer un (1) sp\u00e9cimen des \u00ab Esp\u00e8ces admissibles \u00bb de la liste ci-dessous qui se qualifie comme record d'\u00c9tat par le poids. La liste des Esp\u00e8ces admissibles ci-dessous est subdivis\u00e9e en quatre \u00ab S\u00e9ries de cannes \u00bb qui refl\u00e8tent la Canne officielle qu'un participant doit utiliser pour capturer une esp\u00e8ce admissible particuli\u00e8re (par exemple, vous pouvez capturer un poisson-chat \u00e0 t\u00eate plate avec la canne Big Cat Fever, mais pas avec une canne Striper Stealth). Le premier participant pendant la p\u00e9riode de promotion \u00e0 accomplir ce qui pr\u00e9c\u00e8de et qui se conforme pleinement \u00e0 ces r\u00e8gles officielles (y compris toutes les exigences de v\u00e9rification du gagnant) sera \u00e9ligible pour recevoir le prix de la cat\u00e9gorie Canne (d\u00e9fini ci-dessous).  <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32733dd elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"32733dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">  - Liste des esp\u00e8ces admissibles pour la cat\u00e9gorie Canne et s\u00e9ries de cannes autoris\u00e9es<\/h3><p class=\"elementor-image-box-description\"><h6>S\u00e9rie de cannes Big Cat Fever :<\/h6>\n<ul>\n \t<li>Poisson-chat bleu de l'Arkansas : (Ictalurus furcatus)<\/li>\n \t<li>Poisson-chat \u00e0 t\u00eate plate : (Pylodictis olivaris)<\/li>\n \t<li>Poisson-chat de rivi\u00e8re : (Ictalurus punctatus)<\/li>\n<\/ul>\n<h6>S\u00e9rie de cannes Striper Stealth :<\/h6>\n<ul>\n \t<li>Bar ray\u00e9 : (Morone saxa)<\/li>\n<\/ul>\n<h6>S\u00e9rie Hellcat Rod :<\/h6>\n<ul>\n \t<li>Poisson-chat bleu de l'Arkansas : (Ictalurus furcatus)<\/li>\n \t<li>Poisson-chat \u00e0 t\u00eate plate : (Pylodictis olivaris)<\/li>\n \t<li>Poisson-chat de rivi\u00e8re : (Ictalurus punctatus)<\/li>\n \t<li>Thon rouge : (Thunnus thynnus)<\/li>\n \t<li>Marlin bleu : (Makaira nigricans)<\/li>\n \t<li>Brochet du Nord : (Esox lucius)<\/li>\n \t<li>Coryph\u00e8ne : (Mahi-Mahi\/ Coryphaena hippurus)<\/li>\n \t<li>Maquereau royal : (Scomberomorus cavalla)<\/li>\n \t<li>Fl\u00e9tan de Californie : (Paralichthys californicus)<\/li>\n \t<li>Bar ray\u00e9 : (Morone saxa)<\/li>\n \t<li>Cobia : (Rachycentron Canadum)<\/li>\n \t<li>Thazard-b\u00e2tard : (Acanthomcybium Solandri)<\/li>\n \t<li>Maquereau espagnol : (Scomberomorus Maculatus)<\/li>\n \t<li>Tambour rouge : (Sciaenops Ocelltus)<\/li>\n<\/ul>\n<h6>S\u00e9rie de cannes Precision :<\/h6>\n<ul>\n \t<li>Marigane blanche : (Pomoxis annularis)<\/li>\n \t<li>Marigane noire : (Pomoxis nigromaculatus)<\/li>\n \t<li>Crapet \u00e0 oreilles rouges \u00ab Shellcracker \u00bb : (Lepomis Microlophus)<\/li>\n \t<li>Crapet arlequin : (Lepomis Macrochirus)<\/li>\n<\/ul><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be79b37 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"be79b37\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">5. Comment participer<\/h3><p class=\"elementor-image-box-description\">Si vous croyez de bonne foi avoir captur\u00e9 un record d'\u00c9tat parmi la liste des esp\u00e8ces admissibles dans l'une des cat\u00e9gories de promotion ci-dessus, vous devez promptement (mais en aucun cas plus tard que 48 heures) notifier le Sponsor par un avis pr\u00e9liminaire via courrier certifi\u00e9 indiquant votre conviction et votre intention de soumettre une participation (\u00ab Avis initial \u00bb). L'Avis initial doit indiquer dans quelle cat\u00e9gorie de promotion vous soumettrez une participation, l'esp\u00e8ce admissible, et (sp\u00e9cifiquement pour la cat\u00e9gorie Canne) la s\u00e9rie de cannes. Vous devez conserver une copie de l'Avis initial pour vos dossiers et pour la soumission d'une participation (ci-dessous). Apr\u00e8s la soumission de votre Avis initial, vous devez promptement (mais en aucun cas plus tard que trente (30) jours, sauf autorisation \u00e9crite du Sponsor) obtenir une certification individuelle de record d'\u00c9tat via une demande aupr\u00e8s de votre D\u00e9partement des ressources naturelles de l'\u00c9tat ; Division de la p\u00eache et de la chasse ; Agence des parcs et de la faune ou autre agence gouvernementale similaire responsable de la certification des poissons records d'\u00c9tat (\u00ab Autorit\u00e9 \u00bb). Une fois que votre capture d'esp\u00e8ce admissible a \u00e9t\u00e9 certifi\u00e9e par \u00e9crit par une Autorit\u00e9 comme nouveau poisson record d'\u00c9tat par le poids (un \u00ab Record d'\u00c9tat \u00bb), vous devez promptement (mais en aucun cas plus tard que dix (10) jours \u00e0 compter de la certification du Record d'\u00c9tat) notifier le Sponsor par courrier en incluant les \u00e9l\u00e9ments suivants (qui, une fois soumis, constitueront votre \u00ab Participation \u00bb) :    \n<ul>\n \t<li>Une copie de l'Avis initial ;<\/li>\n \t<li>Une copie de la certification du Record d'\u00c9tat ;<\/li>\n \t<li>Une ou plusieurs photo(s) montrant clairement les \u00e9l\u00e9ments suivants : vous portant l'\u00e9quipement officiel et\/ou utilisant une canne officielle bien visible (chacun doit \u00eatre clair et identifiable sur la photo) tout en tenant, ber\u00e7ant, mettant dans un filet ou d\u00e9montrant autrement votre possession du Record d'\u00c9tat ;<\/li>\n \t<li>Si vous soumettez une candidature pour la Cat\u00e9gorie Canne \u00e0 p\u00eache, votre Record d'\u00c9tat doit avoir \u00e9t\u00e9 \u00e9tabli en utilisant une Canne \u00e0 p\u00eache Officielle et vous devez en attester dans votre Inscription.<\/li>\n<\/ul>\nUne fois qu'une Inscription est re\u00e7ue par le Sponsor, celui-ci \u00e9valuera le contenu de l'Inscription, dans sa totalit\u00e9 et en relation avec le pr\u00e9sent R\u00e8glement Officiel, et prendra une d\u00e9cision, \u00e0 sa seule discr\u00e9tion, quant \u00e0 savoir si l'Inscription r\u00e9pond aux exigences pour recevoir un Prix.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84f8b80 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"84f8b80\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">6. Exclusions et conditions<\/h3><p class=\"elementor-image-box-description\">Aucun Prix ne sera attribu\u00e9 \u00e0 un Participant pr\u00e9sentant un Record d'\u00c9tat qui n'aurait pas \u00e9t\u00e9 \u00e9tabli durant la P\u00e9riode de Promotion. Pour \u00eatre \u00e9ligible \u00e0 un nouveau Record d'\u00c9tat, un Record d'\u00c9tat pour l'Esp\u00e8ce \u00c9ligible doit actuellement exister et l'autorit\u00e9 officielle de tenue des records de l'\u00c9tat correspondant doit avoir maintenu le statut de record pour l'Esp\u00e8ce \u00c9ligible pendant une p\u00e9riode minimale de trois (3) ans avant la soumission de tout nouveau qualifiant pour le Record d'\u00c9tat. Aucun record 'vacant' ou 'vierge' n'est \u00e9ligible au Prix. Tous les poissons doivent \u00eatre captur\u00e9s dans les 'Eaux \u00c9ligibles'. Les Eaux \u00c9ligibles pour la consid\u00e9ration des Records d'\u00c9tat comprendront les eaux des cinquante (50) \u00c9tats-Unis, y compris leurs eaux territoriales respectives, o\u00f9 les esp\u00e8ces sont indig\u00e8nes et dans lesquelles le grand public a un acc\u00e8s absolument libre et illimit\u00e9. Le Golfe du Mexique est inclus, sous r\u00e9serve des eaux territoriales de chaque \u00c9tat et de leurs fronti\u00e8res d\u00e9sign\u00e9es respectives. Les poissons captur\u00e9s dans ou \u00e0 partir d'eaux priv\u00e9es, d'eaux ill\u00e9galement 'hors limites', d'\u00e9tablissements piscicoles ou d'aquaculture, d'eaux priv\u00e9es 'payantes pour p\u00eacher' ou d''eaux de sanctuaires' ne sont pas \u00e9ligibles pour la Promotion. Vous devez respecter toutes les r\u00e8gles et r\u00e9glementations \u00e9tatiques et locales concernant la capture et la remise \u00e0 l'eau. En outre, vous devez observer toutes les directives et l'\u00e9thique de l'industrie concernant la capture et la remise \u00e0 l'eau. Si vous capturez un poisson de la liste des Esp\u00e8ces \u00c9ligibles avec une Canne \u00e0 p\u00eache Officielle, vous devez v\u00e9rifier si l'Esp\u00e8ce \u00c9ligible et la Cat\u00e9gorie de Canne \u00e0 p\u00eache correspondante exigent que le poisson soit rel\u00e2ch\u00e9 vivant.         \n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-008f74b elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"008f74b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">7. Directives de soumission des Inscriptions<\/h3><p class=\"elementor-image-box-description\">\nSi la Participation ne contient pas toutes les informations n\u00e9cessaires telles que d\u00e9crites dans le pr\u00e9sent R\u00e8glement Officiel, celle-ci ne sera pas prise en compte. Veuillez vous assurer de suivre scrupuleusement toutes les directives fournies dans ce R\u00e8glement Officiel. Tous les Participants gagnants doivent signer une D\u00e9claration d'\u00c9ligibilit\u00e9 et une D\u00e9charge de Responsabilit\u00e9 avant de recevoir leur Prix. Si un Participant omet ou refuse de signer et de renvoyer ladite d\u00e9claration, ou tout autre document contractuel ou fiscal dans les dix (10) jours suivant la notification de son statut de gagnant, ce Participant pourra \u00eatre disqualifi\u00e9 de la Promotion. Les Entit\u00e9s de la Promotion d\u00e9clinent toute responsabilit\u00e9 quant aux dommages occasionn\u00e9s au syst\u00e8me informatique d'un Participant ou de toute autre personne r\u00e9sultant de l'acc\u00e8s au Site h\u00e9bergeant le pr\u00e9sent R\u00e8glement Officiel ou de la participation \u00e0 la Promotion. Sans limiter la g\u00e9n\u00e9ralit\u00e9 de ce qui pr\u00e9c\u00e8de, le Sponsor n'est pas responsable des Avis Initiaux ou des Participations ou autres notifications de Promotion incomplets, illisibles, mal adress\u00e9s, mal imprim\u00e9s, tardifs, perdus, endommag\u00e9s, vol\u00e9s ou dont l'affranchissement est incorrect ; ni des r\u00e9seaux, serveurs, satellites, Fournisseurs d'Acc\u00e8s Internet, sites web ou autres connexions perdus, interrompus, inaccessibles ou indisponibles ; ni des erreurs de communication, transmissions informatiques, t\u00e9l\u00e9phoniques ou c\u00e2bl\u00e9es d\u00e9faillantes, brouill\u00e9es, retard\u00e9es ou mal dirig\u00e9es ; ni des dysfonctionnements techniques, pannes ou difficult\u00e9s, erreurs d'impression, erreurs administratives, typographiques ou autres dans l'offre ou l'annonce de la Promotion ou dans tout document de notification de la Promotion, ou d'autres erreurs de quelque nature que ce soit ; ni de la saisie incorrecte ou impr\u00e9cise d'informations, ou de l'\u00e9chec de la capture d'informations. Si, pour une raison quelconque, la Promotion ne peut se d\u00e9rouler comme pr\u00e9vu en raison de causes ind\u00e9pendantes de la volont\u00e9 du Sponsor qui corrompent ou affectent l'administration, la s\u00e9curit\u00e9, l'\u00e9quit\u00e9, l'int\u00e9grit\u00e9 ou le bon d\u00e9roulement de cette Promotion, le Sponsor se r\u00e9serve le droit, \u00e0 sa seule discr\u00e9tion, d'annuler, de mettre fin, de modifier, de suspendre ou de prolonger la Promotion. Toute tentative d'un Participant ou de tout autre individu visant \u00e0 endommager d\u00e9lib\u00e9r\u00e9ment ou \u00e0 saper le fonctionnement l\u00e9gitime de la Promotion, ou \u00e0 importuner, abuser, menacer ou harceler toute autre personne en lien avec la Promotion, constitue une violation des lois p\u00e9nales et civiles et, dans l'\u00e9ventualit\u00e9 d'une telle tentative, le Sponsor se r\u00e9serve le droit de disqualifier l'individu concern\u00e9 et de r\u00e9clamer des dommages-int\u00e9r\u00eats et autres recours \u00e0 cette personne dans toute la mesure permise par la loi. Toute tentative d'un Participant d'inscrire la m\u00eame Participation plus d'une fois par P\u00e9riode de Promotion en utilisant quelque m\u00e9thode que ce soit entra\u00eenera la disqualification du Participant. Le Sponsor se r\u00e9serve le droit de rejeter toute Participation non conforme au pr\u00e9sent R\u00e8glement Officiel. Une Participation ne doit \u00eatre soumise \u00e0 aucune restriction, contractuelle ou autre, qui emp\u00eacherait l'utilisation par le Sponsor de la Participation telle que d\u00e9crite dans les pr\u00e9sentes. Le Participant reconna\u00eet, accepte et garantit que rien dans la Participation n'enfreint les droits d'auteur, les informations confidentielles, les secrets commerciaux, les marques de commerce ou tout autre droit de propri\u00e9t\u00e9 intellectuelle appartenant \u00e0 tout autre Participant ou entit\u00e9, ni ne viole les droits \u00e0 la vie priv\u00e9e ou \u00e0 la publicit\u00e9 d'un Participant, et que toutes les autorisations et permissions n\u00e9cessaires ont \u00e9t\u00e9 obtenues. En soumettant une Participation dans le cadre de la Promotion, un Participant accepte par la pr\u00e9sente que le Sponsor puisse le contacter par message priv\u00e9, e-mail ou t\u00e9l\u00e9phone concernant sa soumission. Le Sponsor se r\u00e9serve le droit, en lien avec toute Participation re\u00e7ue et la v\u00e9rification de la conformit\u00e9 au pr\u00e9sent R\u00e8glement Officiel, d'exiger qu'un Participant se soumette \u00e0 un examen polygraphique \u00e0 la satisfaction du Sponsor.              Il pourra \u00eatre demand\u00e9 au Participant de signer une d\u00e9charge normale et habituelle requise par l'examinateur polygraphique et de pr\u00e9senter les r\u00e9sultats concluants de l'examen polygraphique au Sponsor au plus tard trente (30) jours apr\u00e8s l'examen.\n\nLe non-respect par tout Participant des \u00ab Directives de Soumission des Participations \u00bb et des \u00ab Restrictions relatives aux Participations \u00bb susmentionn\u00e9es, tel que d\u00e9termin\u00e9 par le Sponsor \u00e0 sa seule discr\u00e9tion, peut entra\u00eener la disqualification dudit Participant. Sans limitation, le Sponsor se r\u00e9serve le droit, \u00e0 sa seule discr\u00e9tion, de disqualifier toute Participation qui, selon le jugement exclusif du Sponsor, fait r\u00e9f\u00e9rence, d\u00e9peint ou refl\u00e8te de quelque mani\u00e8re n\u00e9gative le Sponsor, la Promotion, ou tout autre Participant ou entit\u00e9, ou ne respecte pas le pr\u00e9sent R\u00e8glement Officiel, ou si le Sponsor re\u00e7oit une notification concernant toute infraction ou violation potentielle de la loi ou pour toute autre raison \u00e9nonc\u00e9e dans les pr\u00e9sentes. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e030b3 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"0e030b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">8. Utilisation des participations par le sponsor<\/h3><p class=\"elementor-image-box-description\">En soumettant toute Participation en lien avec la Promotion, chaque Participant c\u00e8de par la pr\u00e9sente au Sponsor, sans compensation, tous les droits de propri\u00e9t\u00e9 intellectuelle et autres droits relatifs \u00e0 sa Participation, lesquels droits incluent, sans s'y limiter, le droit illimit\u00e9 du Sponsor d'utiliser, publier, \u00e9diter, modifier, traduire, reproduire, distribuer et mettre \u00e0 la disposition du public dans le monde entier dans tous les m\u00e9dias imprim\u00e9s et \u00e9lectroniques (existants ou futurs) sans limitation de temps de la mani\u00e8re que le Sponsor juge appropri\u00e9e, ainsi que le droit d'inclure son nom et son image en relation avec les utilisations susmentionn\u00e9es. Chaque Participant accepte et comprend que sa Participation peut \u00eatre mise \u00e0 la disposition du public, y compris, sans s'y limiter, sur Internet. Par cons\u00e9quent, le Sponsor ne garantit aucune confidentialit\u00e9 concernant les Participations. En participant \u00e0 la Promotion, en plus de toute autre concession pouvant \u00eatre accord\u00e9e dans tout autre accord conclu entre le Sponsor et tout Participant \u00e0 la Promotion, chaque Participant accorde irr\u00e9vocablement au Sponsor et \u00e0 ses repr\u00e9sentants d\u00e9sign\u00e9s, ainsi qu'\u00e0 leurs successeurs, ayants droit et titulaires de licence respectifs, le droit exclusif d'utiliser le nom, l'image et les informations biographiques dudit Participant et tout m\u00e9dia relatif au Poisson Record d'\u00c9tat officiel, dans tous les m\u00e9dias et \u00e0 toutes fins, y compris, sans s'y limiter, \u00e0 des fins publicitaires et promotionnelles, et d\u00e9gage par la pr\u00e9sente les Entit\u00e9s de la Promotion de toute responsabilit\u00e9 \u00e0 cet \u00e9gard.   <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da298d2 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"da298d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">9. Prix<\/h3><p class=\"elementor-image-box-description\">Le Sponsor attribuera un (1) prix d'un montant de 5 000,00 USD \u00e0 la personne qui remportera de mani\u00e8re concluante la Cat\u00e9gorie Habillement (le \u00ab Prix de la Cat\u00e9gorie Habillement \u00bb) et le Sponsor attribuera un (1) prix d'un montant de 20 000,00 USD \u00e0 la personne qui remportera de mani\u00e8re concluante la Cat\u00e9gorie Canne \u00e0 p\u00eache (le \u00ab Prix de la Cat\u00e9gorie Canne \u00e0 p\u00eache \u00bb). Chacun des \u00e9l\u00e9ments susmentionn\u00e9s est individuellement et collectivement consid\u00e9r\u00e9 comme le \u00ab Prix \u00bb dans le cadre du pr\u00e9sent R\u00e8glement Officiel. Le Sponsor n'attribuera qu'un (1) seul Prix par Cat\u00e9gorie de Promotion. En aucun cas le Sponsor n'attribuera plus de 25 000,00 USD au cours d'une P\u00e9riode de Promotion. Pour plus de clart\u00e9, la m\u00eame personne peut remporter les deux Cat\u00e9gories et recevoir le Prix dans les deux cat\u00e9gories. Les gagnants du Prix, le cas \u00e9ch\u00e9ant, seront seuls responsables de tous les imp\u00f4ts f\u00e9d\u00e9raux, \u00e9tatiques ou locaux, ainsi que des cons\u00e9quences en mati\u00e8re de d\u00e9claration fiscale, et de tous autres frais et co\u00fbts associ\u00e9s au Prix promotionnel applicable.     <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60b4033 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"60b4033\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">10. Avis de non-responsabilit\u00e9<\/h3><p class=\"elementor-image-box-description\">TOUT CE QUI SE TROUVE SUR LE SITE DES ENTIT\u00c9S DE LA PROMOTION \u00ab ET TOUS LES AUTRES MAT\u00c9RIELS D\u00c9COULANT DE CETTE PROMOTION OU Y \u00c9TANT LI\u00c9S SONT FOURNIS \u201cTELS QUELS\u201d SANS GARANTIE D'AUCUNE SORTE, EXPRESSE OU IMPLICITE, Y COMPRIS, MAIS SANS S'Y LIMITER, LES GARANTIES IMPLICITES DE QUALIT\u00c9 MARCHANDE, D'AD\u00c9QUATION \u00c0 UN USAGE PARTICULIER OU DE NON-CONTREFA\u00c7ON. EN OUTRE, LES ENTIT\u00c9S DE LA PROMOTION NE FONT AUCUNE D\u00c9CLARATION QUANT \u00c0 L'AD\u00c9QUATION OU \u00c0 LA DISPONIBILIT\u00c9 DES MAT\u00c9RIELS DE LA PROMOTION POUR UNE UTILISATION EN TOUT LIEU ET \u00c0 TOUT MOMENT. IL INCOMBE AU PARTICIPANT DE S'ASSURER QUE L'ACC\u00c8S AUX SITES DES ENTIT\u00c9S DE LA PROMOTION \u00bb ET LA PARTICIPATION \u00c0 LA PROMOTION SONT L\u00c9GAUX ET NON INTERDITS PAR LES LOIS DE LA JURIDICTION DONT LE PARTICIPANT EST CITOYEN.  <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff59901 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"ff59901\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">11. Indemnisation<\/h3><p class=\"elementor-image-box-description\">En participant, vous acceptez que les Entit\u00e9s de la Promotion soient indemnis\u00e9es, d\u00e9gag\u00e9es de toute responsabilit\u00e9 et tenues indemnes par vous de toute responsabilit\u00e9, pour tout dommage, blessure ou perte de quelque nature que ce soit caus\u00e9 \u00e0 des personnes, y compris le d\u00e9c\u00e8s, ou \u00e0 des biens (y compris les animaux de compagnie), r\u00e9sultant directement ou indirectement de l'acceptation, de la possession, de la mauvaise utilisation ou de l'utilisation du Prix ou de votre participation \u00e0 la Promotion ou \u00e0 toute activit\u00e9 li\u00e9e \u00e0 la Promotion, de quelque mani\u00e8re que ce soit.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93ea32a elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"93ea32a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">12. Limitation de responsabilit\u00e9<\/h3><p class=\"elementor-image-box-description\">Les Entit\u00e9s de la Promotion ne sont pas responsables et sont par la pr\u00e9sente d\u00e9gag\u00e9es de toute responsabilit\u00e9 en ce qui concerne :\n<ul>\n \t<li>(a) toute erreur d'impression, typographique, m\u00e9canique ou autre dans l'impression, l'offre ou l'administration de la Promotion ou dans l'annonce du Prix ;<\/li>\n \t<li>(b) les participations ou courriels perdus, tardifs, illisibles, mal achemin\u00e9s ou non livr\u00e9s ;<\/li>\n \t<li>(c) toute participation soumise d'une mani\u00e8re qui n'est pas express\u00e9ment autoris\u00e9e par le pr\u00e9sent R\u00e8glement Officiel ;<\/li>\n \t<li>(d) la perte, l'interruption ou l'indisponibilit\u00e9 des connexions satellite, r\u00e9seau, fournisseur de services Internet, Site ou autres, la disponibilit\u00e9, l'accessibilit\u00e9 ou la congestion du trafic, ou les erreurs de communication, ou la d\u00e9faillance du mat\u00e9riel informatique, du r\u00e9seau, du t\u00e9l\u00e9phone ou des c\u00e2bles, ou les d\u00e9faillances techniques, ou les transmissions brouill\u00e9es, m\u00e9lang\u00e9es, retard\u00e9es ou mal achemin\u00e9es, ou les dysfonctionnements du mat\u00e9riel ou des logiciels informatiques, les pannes ou les difficult\u00e9s ;<\/li>\n \t<li>(e) d'autres erreurs de quelque nature que ce soit, qu'elles soient humaines, m\u00e9caniques, \u00e9lectroniques ou de r\u00e9seau, ou la saisie incorrecte ou inexacte de la participation ou d'autres informations, ou l'\u00e9chec de la saisie ou la perte de telles informations ;<\/li>\n \t<li>(f) toute information incorrecte ou inexacte, qu'elle soit caus\u00e9e par les utilisateurs du Site ou par tout \u00e9quipement ou programmation associ\u00e9 \u00e0 la Promotion ou utilis\u00e9 dans celle-ci ;<\/li>\n \t<li>(g) toute erreur, omission, interruption, suppression, d\u00e9faut ou retard de fonctionnement ou de transmission, panne de ligne de communication, vol ou destruction ou acc\u00e8s non autoris\u00e9 \u00e0 tout Site, ou falsification ou piratage de tout Site ; ou<\/li>\n \t<li>(h) tout pr\u00e9judice ou dommage caus\u00e9 \u00e0 l'ordinateur du Participant ou de toute autre personne, li\u00e9 \u00e0 ou r\u00e9sultant de la participation \u00e0 la Promotion ou du t\u00e9l\u00e9chargement ou de la copie de mat\u00e9riels provenant du Site ou de son utilisation.<\/li>\n<\/ul>\nEN AUCUN CAS LES ENTIT\u00c9S DE LA PROMOTION NE SERONT RESPONSABLES OU TENUES POUR RESPONSABLES DE QUELCONQUES DOMMAGES OU PERTES DE QUELQUE NATURE QUE CE SOIT, Y COMPRIS LES DOMMAGES DIRECTS, INDIRECTS, ACCESSOIRES, CONS\u00c9CUTIFS OU PUNITIFS R\u00c9SULTANT DE LA PARTICIPATION DU PARTICIPANT \u00c0 LA PROMOTION. DANS TOUS LES CAS, LA RESPONSABILIT\u00c9 TOTALE DES ENTIT\u00c9S DE LA PROMOTION EN VERTU OU LI\u00c9E \u00c0 CETTE PROMOTION NE D\u00c9PASSERA PAS 100,00 USD. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c49a6a0 elementor-position-left elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"c49a6a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"50\" height=\"49\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png\" class=\"attachment-full size-full wp-image-48\" alt=\"\" title=\"Icon (1) - Catch the Fever Outdoors\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1.png 50w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-1-10x10.webp 10w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">13. Conditions g\u00e9n\u00e9rales<\/h3><p class=\"elementor-image-box-description\">En participant, les Participants conviennent que toutes les questions concernant l'interpr\u00e9tation, la validit\u00e9 et l'applicabilit\u00e9 du pr\u00e9sent R\u00e8glement Officiel, les droits et obligations des Participants, ou les droits et obligations du Sponsor en relation avec la Promotion, seront r\u00e9gies et interpr\u00e9t\u00e9es conform\u00e9ment aux lois de l'\u00c9tat de Caroline du Nord, sans donner effet \u00e0 aucun choix de loi ou conflit de r\u00e8gles de droit, et que toute affaire ou proc\u00e9dure se d\u00e9roulera dans l'\u00c9tat de Caroline du Nord. Le Sponsor se r\u00e9serve le droit, \u00e0 sa seule discr\u00e9tion, de disqualifier tout individu qui, selon lui, pourrait alt\u00e9rer le processus de participation ou le d\u00e9roulement de la Promotion ou de tout Site associ\u00e9, pourrait agir en violation des conditions d'un Site associ\u00e9 ou du pr\u00e9sent R\u00e8glement Officiel, ou pourrait agir de mani\u00e8re antisportive ou perturbatrice, ou avec l'intention de menacer, d'abuser ou de harceler toute autre personne. Si une ou plusieurs dispositions du pr\u00e9sent R\u00e8glement Officiel sont jug\u00e9es invalides ou inapplicables, toutes les autres dispositions resteront pleinement en vigueur. Une renonciation \u00e0 toute disposition du pr\u00e9sent R\u00e8glement Officiel doit \u00eatre faite par \u00e9crit, et une renonciation dans un cas ou pour une disposition ne sera pas consid\u00e9r\u00e9e comme une renonciation pour tout autre cas ou disposition.   \n\n\n<br><br>Derni\u00e8re r\u00e9vision - 20 ao\u00fbt 2014<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1557a85 elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"1557a85\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf72a11\" data-id=\"cf72a11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8fbfded elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8fbfded\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4eb2564\" data-id=\"4eb2564\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bc7ff2f\" data-id=\"bc7ff2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eec9d8e elementor-widget elementor-widget-video\" data-id=\"eec9d8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.facebook.com\\\/watch\\\/?v=780335102738147&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/xstore.8theme.com\\\/elementor\\\/demos\\\/sneakers\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2021\\\/08\\\/Icon-3.png&quot;,&quot;id&quot;:50,&quot;size&quot;:&quot;&quot;},&quot;lightbox&quot;:&quot;yes&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;lightbox_content_animation&quot;:&quot;fadeInUp&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-lightbox\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:null,&quot;autoplay&quot;:&quot;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-eec9d8e&quot;,&quot;entranceAnimation&quot;:&quot;fadeInUp&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJ5b3V0dWJlIiwidXJsIjpudWxsLCJhdXRvcGxheSI6IiIsIm1vZGFsT3B0aW9ucyI6eyJpZCI6ImVsZW1lbnRvci1saWdodGJveC1lZWM5ZDhlIiwiZW50cmFuY2VBbmltYXRpb24iOiJmYWRlSW5VcCIsImVudHJhbmNlQW5pbWF0aW9uX3RhYmxldCI6IiIsImVudHJhbmNlQW5pbWF0aW9uX21vYmlsZSI6IiIsInZpZGVvQXNwZWN0UmF0aW8iOiIxNjkifX0%3D\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-3.png\" class=\"attachment-full size-full wp-image-50\" alt=\"\" srcset=\"https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-3.png 80w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-3-1x1.webp 1w, https:\/\/catchthefever.com\/wp-content\/uploads\/2021\/08\/Icon-3-10x10.webp 10w\" sizes=\"(max-width: 80px) 100vw, 80px\" title=\"Icon (3) - Catch the Fever Outdoors\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7894a44\" data-id=\"7894a44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6ee2e5 elementor-widget elementor-widget-heading\" data-id=\"e6ee2e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Don de 10 000 $ \u00e0 un service d'incendie. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80f50c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"80f50c7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67da966\" data-id=\"67da966\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-395a868 elementor-widget elementor-widget-heading\" data-id=\"395a868\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9cits de succ\u00e8s de paiements mis en vedette<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-4d0eefb3 twbb_section e-flex e-con-boxed e-con e-parent\" data-id=\"4d0eefb3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-67206789 e-con-full e-flex e-con e-child\" data-id=\"67206789\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ecc6fa5 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6ecc6fa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ils ont remport\u00e9 les prix Catch the Fever <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef76b38 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ef76b38\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Catch The Fever r\u00e9compense les meilleurs p\u00eacheurs de la Nation. <\/p><p>Jetez un coup d&rsquo;\u0153il aux pr\u00e9c\u00e9dents laur\u00e9ats et d\u00e9couvrez combien ils ont gagn\u00e9. <\/p><p>Serez-vous le prochain ?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-435d2792 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"435d2792\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tout le monde peut participer*<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Diverses fa\u00e7ons d'\u00eatre \u00e9ligible \u00e0 un paiement<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">P\u00eachez plus de 18 esp\u00e8ces de poissons (eau douce &amp; eau sal\u00e9e)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4326692 elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"4326692\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=476&amp;href=https%3A%2F%2Fwww.facebook.com%2Freel%2F985708149841133%2F&amp;show_text=true&amp;width=267&amp;t=0\" width=\"267\" height=\"591\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68de49d twbb_section elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"68de49d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c10ac77 e-con-full e-flex e-con e-child\" data-id=\"c10ac77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad76448 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ad76448\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un p\u00eacheur chanceux fait don de son gain \u00e0 son service d'incendie local<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dcc223 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1dcc223\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quand le talent rencontre la g\u00e9n\u00e9rosit\u00e9 : Gagner un prix gr\u00e2ce \u00e0 vos prouesses est exceptionnel. Mais c&rsquo;est extraordinaire lorsque votre compassion et votre souci des autres, de votre communaut\u00e9, sont votre priorit\u00e9 et que vous faites don de votre gain \u00e0 votre service d&rsquo;incendie local.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c2817c elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2c2817c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">10 000 $ donn\u00e9s au service d'incendie volontaire de Gasburg<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Joey Baird est d\u00e9tenteur du record d'\u00c9tat de Caroline du Nord pour le poisson-chat bleu<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37aa2a1 elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"37aa2a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&amp;href=https%3A%2F%2Fwww.facebook.com%2FCatchtheFeverOutdoors%2Fvideos%2F780335102738147%2F&amp;show_text=true&amp;width=560&amp;t=0\" width=\"560\" height=\"429\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b457b4 e-flex e-con-boxed e-con e-parent\" data-id=\"3b457b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Catch The Fever vous r\u00e9compense pour votre fid\u00e9lit\u00e9, votre passion et vos comp\u00e9tences. D\u00e9couvrez comment d\u00e9bloquer jusqu&rsquo;\u00e0 25 000 $ de prix en p\u00eachant avec nos cannes et\/ou en portant nos v\u00eatements.  <\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-75286","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Gagnez jusqu&#039;\u00e0 25 000 $ en utilisant les produits CTF ! Nous r\u00e9compensons les p\u00eacheurs aux \u00c9tats-Unis pour leurs comp\u00e9tences lorsqu\u2019ils p\u00eachent avec Catch The Fever. Les gains peuvent \u00eatre consid\u00e9rables. D\u00e9couvrez si vous \u00eates \u00e9ligible, comment participer, quelles s\u00e9ries de cannes et\/ou v\u00eatements vous pouvez utiliser dans quelles circonstances pour potentiellement gagner jusqu\u2019\u00e0 25\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/catchthefever.com\/fr\/affilies\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Catch The Fever Outdoors - The Brand That Pays To Fish | Next Generation Freshwater and Saltwater Fishing Rods\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Affili\u00e9s - Catch The Fever Outdoors\" \/>\n\t\t<meta property=\"og:description\" content=\"Gagnez jusqu&#039;\u00e0 25 000 $ en utilisant les produits CTF ! Nous r\u00e9compensons les p\u00eacheurs aux \u00c9tats-Unis pour leurs comp\u00e9tences lorsqu\u2019ils p\u00eachent avec Catch The Fever. Les gains peuvent \u00eatre consid\u00e9rables. D\u00e9couvrez si vous \u00eates \u00e9ligible, comment participer, quelles s\u00e9ries de cannes et\/ou v\u00eatements vous pouvez utiliser dans quelles circonstances pour potentiellement gagner jusqu\u2019\u00e0 25\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/catchthefever.com\/fr\/affilies\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-08-21T02:31:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-09-17T17:29:34+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Affili\u00e9s - Catch The Fever Outdoors\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Gagnez jusqu&#039;\u00e0 25 000 $ en utilisant les produits CTF ! Nous r\u00e9compensons les p\u00eacheurs aux \u00c9tats-Unis pour leurs comp\u00e9tences lorsqu\u2019ils p\u00eachent avec Catch The Fever. Les gains peuvent \u00eatre consid\u00e9rables. D\u00e9couvrez si vous \u00eates \u00e9ligible, comment participer, quelles s\u00e9ries de cannes et\/ou v\u00eatements vous pouvez utiliser dans quelles circonstances pour potentiellement gagner jusqu\u2019\u00e0 25\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/affilies\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/affilies\\\/#listItem\",\"name\":\"Affili\\u00e9s\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/affilies\\\/#listItem\",\"position\":2,\"name\":\"Affili\\u00e9s\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/#organization\",\"name\":\"Catch The Fever Outdoors\",\"description\":\"The Brand That Pays To Fish | Next Generation Freshwater and Saltwater Fishing Rods\",\"url\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/\",\"email\":\"support@catchthefever.com\",\"telephone\":\"+19842349634\",\"foundingDate\":\"2016-03-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":20,\"maxValue\":40},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/catchthefever.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Catch-The-Fever-Logo-Decal-922x2222-1.webp\",\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/affilies\\\/#organizationLogo\",\"width\":869,\"height\":430},\"image\":{\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/affilies\\\/#organizationLogo\"},\"address\":{\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"1458 Old Durham Rd.\",\"postalCode\":\"27573\",\"addressLocality\":\"Roxboro\",\"addressRegion\":\"NC\",\"addressCountry\":\"US\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/affilies\\\/#webpage\",\"url\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/affilies\\\/\",\"name\":\"Affili\\u00e9s - Catch The Fever Outdoors\",\"description\":\"Gagnez jusqu'\\u00e0 25 000 $ en utilisant les produits CTF ! Nous r\\u00e9compensons les p\\u00eacheurs aux \\u00c9tats-Unis pour leurs comp\\u00e9tences lorsqu\\u2019ils p\\u00eachent avec Catch The Fever. Les gains peuvent \\u00eatre consid\\u00e9rables. D\\u00e9couvrez si vous \\u00eates \\u00e9ligible, comment participer, quelles s\\u00e9ries de cannes et\\\/ou v\\u00eatements vous pouvez utiliser dans quelles circonstances pour potentiellement gagner jusqu\\u2019\\u00e0 25\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/affilies\\\/#breadcrumblist\"},\"datePublished\":\"2024-08-20T21:31:34-05:00\",\"dateModified\":\"2025-09-17T12:29:34-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/\",\"name\":\"Catch The Fever Outdoors\",\"description\":\"The Brand That Pays To Fish | Next Generation Freshwater and Saltwater Fishing Rods\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/catchthefever.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Affili\u00e9s - Catch The Fever Outdoors<\/title>\n\n","aioseo_head_json":{"title":"Affili\u00e9s - Catch The Fever Outdoors","description":"Gagnez jusqu'\u00e0 25 000 $ en utilisant les produits CTF ! Nous r\u00e9compensons les p\u00eacheurs aux \u00c9tats-Unis pour leurs comp\u00e9tences lorsqu\u2019ils p\u00eachent avec Catch The Fever. Les gains peuvent \u00eatre consid\u00e9rables. D\u00e9couvrez si vous \u00eates \u00e9ligible, comment participer, quelles s\u00e9ries de cannes et\/ou v\u00eatements vous pouvez utiliser dans quelles circonstances pour potentiellement gagner jusqu\u2019\u00e0 25","canonical_url":"https:\/\/catchthefever.com\/fr\/affilies\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/catchthefever.com\/fr\/affilies\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/catchthefever.com\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/catchthefever.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/catchthefever.com\/fr\/affilies\/#listItem","name":"Affili\u00e9s"}},{"@type":"ListItem","@id":"https:\/\/catchthefever.com\/fr\/affilies\/#listItem","position":2,"name":"Affili\u00e9s","previousItem":{"@type":"ListItem","@id":"https:\/\/catchthefever.com\/fr\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/catchthefever.com\/fr\/#organization","name":"Catch The Fever Outdoors","description":"The Brand That Pays To Fish | Next Generation Freshwater and Saltwater Fishing Rods","url":"https:\/\/catchthefever.com\/fr\/","email":"support@catchthefever.com","telephone":"+19842349634","foundingDate":"2016-03-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":20,"maxValue":40},"logo":{"@type":"ImageObject","url":"https:\/\/catchthefever.com\/wp-content\/uploads\/2024\/08\/Catch-The-Fever-Logo-Decal-922x2222-1.webp","@id":"https:\/\/catchthefever.com\/fr\/affilies\/#organizationLogo","width":869,"height":430},"image":{"@id":"https:\/\/catchthefever.com\/fr\/affilies\/#organizationLogo"},"address":{"@id":"https:\/\/catchthefever.com\/fr\/#postaladdress","@type":"PostalAddress","streetAddress":"1458 Old Durham Rd.","postalCode":"27573","addressLocality":"Roxboro","addressRegion":"NC","addressCountry":"US"}},{"@type":"WebPage","@id":"https:\/\/catchthefever.com\/fr\/affilies\/#webpage","url":"https:\/\/catchthefever.com\/fr\/affilies\/","name":"Affili\u00e9s - Catch The Fever Outdoors","description":"Gagnez jusqu'\u00e0 25 000 $ en utilisant les produits CTF ! Nous r\u00e9compensons les p\u00eacheurs aux \u00c9tats-Unis pour leurs comp\u00e9tences lorsqu\u2019ils p\u00eachent avec Catch The Fever. Les gains peuvent \u00eatre consid\u00e9rables. D\u00e9couvrez si vous \u00eates \u00e9ligible, comment participer, quelles s\u00e9ries de cannes et\/ou v\u00eatements vous pouvez utiliser dans quelles circonstances pour potentiellement gagner jusqu\u2019\u00e0 25","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/catchthefever.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/catchthefever.com\/fr\/affilies\/#breadcrumblist"},"datePublished":"2024-08-20T21:31:34-05:00","dateModified":"2025-09-17T12:29:34-05:00"},{"@type":"WebSite","@id":"https:\/\/catchthefever.com\/fr\/#website","url":"https:\/\/catchthefever.com\/fr\/","name":"Catch The Fever Outdoors","description":"The Brand That Pays To Fish | Next Generation Freshwater and Saltwater Fishing Rods","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/catchthefever.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Catch The Fever Outdoors - The Brand That Pays To Fish | Next Generation Freshwater and Saltwater Fishing Rods","og:type":"article","og:title":"Affili\u00e9s - Catch The Fever Outdoors","og:description":"Gagnez jusqu'\u00e0 25 000 $ en utilisant les produits CTF ! Nous r\u00e9compensons les p\u00eacheurs aux \u00c9tats-Unis pour leurs comp\u00e9tences lorsqu\u2019ils p\u00eachent avec Catch The Fever. Les gains peuvent \u00eatre consid\u00e9rables. D\u00e9couvrez si vous \u00eates \u00e9ligible, comment participer, quelles s\u00e9ries de cannes et\/ou v\u00eatements vous pouvez utiliser dans quelles circonstances pour potentiellement gagner jusqu\u2019\u00e0 25","og:url":"https:\/\/catchthefever.com\/fr\/affilies\/","article:published_time":"2024-08-21T02:31:34+00:00","article:modified_time":"2025-09-17T17:29:34+00:00","twitter:card":"summary_large_image","twitter:title":"Affili\u00e9s - Catch The Fever Outdoors","twitter:description":"Gagnez jusqu'\u00e0 25 000 $ en utilisant les produits CTF ! Nous r\u00e9compensons les p\u00eacheurs aux \u00c9tats-Unis pour leurs comp\u00e9tences lorsqu\u2019ils p\u00eachent avec Catch The Fever. Les gains peuvent \u00eatre consid\u00e9rables. D\u00e9couvrez si vous \u00eates \u00e9ligible, comment participer, quelles s\u00e9ries de cannes et\/ou v\u00eatements vous pouvez utiliser dans quelles circonstances pour potentiellement gagner jusqu\u2019\u00e0 25"},"aioseo_meta_data":{"post_id":"75286","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 04:36:56","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2025-06-11 02:02:52","updated":"2026-05-13 04:36:56"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/catchthefever.com\/fr\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2192<\/span><span class=\"aioseo-breadcrumb\">\n\tAffili\u00e9s\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/catchthefever.com\/fr\/"},{"label":"Affili\u00e9s","link":"https:\/\/catchthefever.com\/fr\/affilies\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/catchthefever.com\/fr\/wp-json\/wp\/v2\/pages\/75286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catchthefever.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/catchthefever.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/catchthefever.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/catchthefever.com\/fr\/wp-json\/wp\/v2\/comments?post=75286"}],"version-history":[{"count":0,"href":"https:\/\/catchthefever.com\/fr\/wp-json\/wp\/v2\/pages\/75286\/revisions"}],"wp:attachment":[{"href":"https:\/\/catchthefever.com\/fr\/wp-json\/wp\/v2\/media?parent=75286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}